{"id":3574,"date":"2023-12-21T09:10:49","date_gmt":"2023-12-21T12:10:49","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/cony-80-anos\/"},"modified":"2023-12-21T09:10:49","modified_gmt":"2023-12-21T12:10:49","slug":"cony-80-anos","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/cony-80-anos\/","title":{"rendered":"CONY, 80 ANOS"},"content":{"rendered":"<p>O jornalista e escritor carioca Carlos Heitor Cony completou 80 anos. L\u00facido, capaz, ir\u00f4nico, irreverente e lido. Os n\u00fameros redondos s\u00e3o importantes, devem ser lembrados e comemorados, pois definem \u00e9pocas diferentes nas vidas das pessoas. Cada \u00e9poca com seu encanto e dores. Sou leitor cativo de Cony desde a minha juventude. Ele \u00e9 refer\u00eancia do jornalismo brasileiro, expoente da cr\u00f4nica e consagrado palestrante.<br \/>\nH\u00e1 dois fatos na vida de Cony que considero importantes, pelo menos na minha vis\u00e3o. Um \u00e9 o conte\u00fado de sua vida como jornalista combativo e temido, o outro \u00e9 a obra liter\u00e1ria que criou, parecendo sem pretens\u00f5es e que o consagrou. Destaco, entre tudo o que escreveu, o livro \u201cQuase Mem\u00f3ria, quase romance\u201d em que fala de sua vida, da inf\u00e2ncia suburbana, do seu tempo de semin\u00e1rio com a falta de f\u00e9 inata, fam\u00edlia, do amor extremado ao pai e, como suspense constante, a exist\u00eancia de um pacote atado por barbante que nunca \u00e9 aberto at\u00e9 a \u00faltima p\u00e1gina da hist\u00f3ria.<br \/>\nEm 28 de fevereiro de 1999, escrevi uma cr\u00f4nica aqui neste mesmo local do Di\u00e1rio do Nordeste, com o t\u00edtulo \u201cEu, filho. Eu, pai. Eu, filho\u201d, e a iniciei assim: \u201cTodos n\u00f3s, com o tempo, vamos ficando revisionistas. O que era, passa a n\u00e3o ser mais daquela forma, as tintas tomam tons amenos e a acidez das cr\u00edticas perde as peremptoriedades\u201d, e a\u00ed me refiro a Machado de Assis em Dom Casmurro.<br \/>\nNessa cr\u00f4nica de 99 falo de autores brasileiros, Machado de Assis, Zuenir Ventura, \u00c9rico e Luiz Fernando Ver\u00edssimo, mas o destaque \u00e9 Cony. L\u00e1 pelo meio, digo: \u201cCarlos Heitor Cony, escritor e jornalista, a quem todo leitor de jornal conhece ou deveria conhecer, resolve revisitar as rela\u00e7\u00f5es com o seu pai, jornalista que quase deu certo, j\u00e1 morto. E o faz com olhos de um homem maduro, j\u00e1 setent\u00e3o, o que lhe permite sempre dourar a p\u00edlula e transformar um pai comum, sem grandes feitos e muitos defeitos, em um tipo que vai nos apaixonando com seus quase acertos, seus projetos inacabados, a preocupa\u00e7\u00e3o com a educa\u00e7\u00e3o dos filhos, o microcosmo do seu mundo suburbano e uma mitomania que se transforma em folclore\u201d.<br \/>\n\u00c9 este homem simples e grande, que soube e ainda sabe ser filho de pai morto &#8211; e que chorou por escrito com a perda de sua cadela de estima\u00e7\u00e3o &#8211; que est\u00e1 merecendo os nossos parab\u00e9ns pelo que nos deleita e ensina. Cony.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\ncronista<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 19\/03\/2006.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O jornalista e escritor carioca Carlos Heitor Cony completou 80 anos. L\u00facido, capaz, ir\u00f4nico, irreverente e lido. Os n\u00fameros redondos s\u00e3o importantes, devem ser lembrados e comemorados, pois definem \u00e9pocas diferentes nas vidas das pessoas. Cada \u00e9poca com seu encanto e dores. Sou leitor cativo de Cony desde a minha juventude. Ele \u00e9 refer\u00eancia do jornalismo brasileiro, expoente da cr\u00f4nica e consagrado palestrante.<br \/>\nH\u00e1 dois fatos na vida de Cony que considero importantes, pelo menos na minha vis\u00e3o. Um \u00e9 o conte\u00fado de sua vida como jornalista combativo e temido, o outro \u00e9 a obra liter\u00e1ria que criou, parecendo sem pretens\u00f5es e que o consagrou. Destaco, entre tudo o que escreveu, o livro \u201cQuase Mem\u00f3ria, quase romance\u201d em que fala de sua vida, da inf\u00e2ncia suburbana, do seu tempo de semin\u00e1rio com a falta de f\u00e9 inata, fam\u00edlia, do amor extremado ao pai e, como suspense constante, a exist\u00eancia de um pacote atado por barbante que nunca \u00e9 aberto at\u00e9 a \u00faltima p\u00e1gina da hist\u00f3ria.<br \/>\nEm 28 de fevereiro de 1999, escrevi uma cr\u00f4nica aqui neste mesmo local do Di\u00e1rio do Nordeste, com o t\u00edtulo \u201cEu, filho. Eu, pai. Eu, filho\u201d, e a iniciei assim: \u201cTodos n\u00f3s, com o tempo, vamos ficando revisionistas. O que era, passa a n\u00e3o ser mais daquela forma, as tintas tomam tons amenos e a acidez das cr\u00edticas perde as peremptoriedades\u201d, e a\u00ed me refiro a Machado de Assis em Dom Casmurro.<br \/>\nNessa cr\u00f4nica de 99 falo de autores brasileiros, Machado de Assis, Zuenir Ventura, \u00c9rico e Luiz Fernando Ver\u00edssimo, mas o destaque \u00e9 Cony. L\u00e1 pelo meio, digo: \u201cCarlos Heitor Cony, escritor e jornalista, a quem todo leitor de jornal conhece ou deveria conhecer, resolve revisitar as rela\u00e7\u00f5es com o seu pai, jornalista que quase deu certo, j\u00e1 morto. E o faz com olhos de um homem maduro, j\u00e1 setent\u00e3o, o que lhe permite sempre dourar a p\u00edlula e transformar um pai comum, sem grandes feitos e muitos defeitos, em um tipo que vai nos apaixonando com seus quase acertos, seus projetos inacabados, a preocupa\u00e7\u00e3o com a educa\u00e7\u00e3o dos filhos, o microcosmo do seu mundo suburbano e uma mitomania que se transforma em folclore\u201d.<br \/>\n\u00c9 este homem simples e grande, que soube e ainda sabe ser filho de pai morto &#8211; e que chorou por escrito com a perda de sua cadela de estima\u00e7\u00e3o &#8211; que est\u00e1 merecendo os nossos parab\u00e9ns pelo que nos deleita e ensina. Cony.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\ncronista<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 19\/03\/2006.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3574","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3574"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3574\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}