{"id":3577,"date":"2023-12-21T09:10:49","date_gmt":"2023-12-21T12:10:49","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/a-praia-de-lua-grande\/"},"modified":"2023-12-21T09:10:49","modified_gmt":"2023-12-21T12:10:49","slug":"a-praia-de-lua-grande","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/a-praia-de-lua-grande\/","title":{"rendered":"A PRAIA DE LUA GRANDE"},"content":{"rendered":"<p>O m\u00eas de mar\u00e7o de 2006 teve uma brisa forte soprando sobre a maturidade de Ednilo So\u00e1rez, debutante no dif\u00edcil campo do romance. A brisa chegava do mar, ali em frente de quem entra no Ideal Clube pela Monsenhor Tabosa. At\u00e9 uma lua grande (ou seriam os refletores?) aparecia, despistava e voltava trazendo os personagens do romance de estreia do adolescente que deixou sua terra, entrou na Marinha, andou por mares in\u00e9ditos em n\u00f3s lentos, de olhos \u00e0 escuta. Mas, voltando apascentado \u00e0 terra-mar, n\u00e3o retratou os mares dos outros, mas o das nossas paragens. Ateve-se a falar de pessoas, intrigas, assassinato e amarrar um desfecho que permite, se o desejar, sequencia-lo.<br \/>\nTinha mais gente por l\u00e1 que em Lua Grande e, certamente, de patamares diferentes, formava um microcosmo assaz rico para os olhos v\u00e1rios dos que, convidados, chegam nos trinques e ficam a passear de livro \u00e0s m\u00e3os, como se fosse uma prenda arrematada em preg\u00e3o liter\u00e1rio. Mas n\u00e3o era um preg\u00e3o, posto que um sarau de classe, digno de qualquer recanto, de Lua Grande \u00e0 j\u00e1 grande e marejada Fortaleza.<br \/>\nO livro \u00e9 um primor gr\u00e1fico, os breves coment\u00e1rios na sua orelha esquerda ecoam s\u00f3brios. A educa\u00e7\u00e3o de Ednilo pediu que agradecesse e dedicasse os seus dois anos de labor. Reconhecido ao jeito de sempre, descontra\u00eddo, gentil, aberto e leal. A apresenta\u00e7\u00e3o de Carlos Augusto Viana \u00e9 a reafirma\u00e7\u00e3o de seu talento, quer como poeta, ensa\u00edsta e cr\u00edtico. Com sentido did\u00e1tico e erudi\u00e7\u00e3o, como se aquelas p\u00e1ginas certificassem o seu estilo e com aprumo atestasse o \u201cimprimatur\u201d, no reconhecer pessoas, falar de coisas e sentimentos de forma apropriada. Tudo nos conformes.<br \/>\nMas, e o livro? Vou deixar que cada um que o tenha comprado ou o compre, fa\u00e7a a tarefa de ir descobrindo a jangada \u201cBrisa do Mar\u201d, seus tripulantes, as figuras mais importantes de Lua Grande, o Conselho Municipal, a visita do Governador, as intrigas, o crime em Fortaleza e o enredo que se renova a cada cap\u00edtulo, como se fosse uma breve narrativa que vai tecendo n\u00f3s de marinheiros.<br \/>\nPor \u00faltimo, este livro \u00e9 prova ratificada de cearensidade, mar de escava\u00e7\u00e3o existencial, praia cheia de simplicidade, entrela\u00e7amento e areias onde dramas, percal\u00e7os e alegrias se encontram.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\ncronista<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 09\/04\/2006.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00eas de mar\u00e7o de 2006 teve uma brisa forte soprando sobre a maturidade de Ednilo So\u00e1rez, debutante no dif\u00edcil campo do romance. A brisa chegava do mar, ali em frente de quem entra no Ideal Clube pela Monsenhor Tabosa. At\u00e9 uma lua grande (ou seriam os refletores?) aparecia, despistava e voltava trazendo os personagens do romance de estreia do adolescente que deixou sua terra, entrou na Marinha, andou por mares in\u00e9ditos em n\u00f3s lentos, de olhos \u00e0 escuta. Mas, voltando apascentado \u00e0 terra-mar, n\u00e3o retratou os mares dos outros, mas o das nossas paragens. Ateve-se a falar de pessoas, intrigas, assassinato e amarrar um desfecho que permite, se o desejar, sequencia-lo.<br \/>\nTinha mais gente por l\u00e1 que em Lua Grande e, certamente, de patamares diferentes, formava um microcosmo assaz rico para os olhos v\u00e1rios dos que, convidados, chegam nos trinques e ficam a passear de livro \u00e0s m\u00e3os, como se fosse uma prenda arrematada em preg\u00e3o liter\u00e1rio. Mas n\u00e3o era um preg\u00e3o, posto que um sarau de classe, digno de qualquer recanto, de Lua Grande \u00e0 j\u00e1 grande e marejada Fortaleza.<br \/>\nO livro \u00e9 um primor gr\u00e1fico, os breves coment\u00e1rios na sua orelha esquerda ecoam s\u00f3brios. A educa\u00e7\u00e3o de Ednilo pediu que agradecesse e dedicasse os seus dois anos de labor. Reconhecido ao jeito de sempre, descontra\u00eddo, gentil, aberto e leal. A apresenta\u00e7\u00e3o de Carlos Augusto Viana \u00e9 a reafirma\u00e7\u00e3o de seu talento, quer como poeta, ensa\u00edsta e cr\u00edtico. Com sentido did\u00e1tico e erudi\u00e7\u00e3o, como se aquelas p\u00e1ginas certificassem o seu estilo e com aprumo atestasse o \u201cimprimatur\u201d, no reconhecer pessoas, falar de coisas e sentimentos de forma apropriada. Tudo nos conformes.<br \/>\nMas, e o livro? Vou deixar que cada um que o tenha comprado ou o compre, fa\u00e7a a tarefa de ir descobrindo a jangada \u201cBrisa do Mar\u201d, seus tripulantes, as figuras mais importantes de Lua Grande, o Conselho Municipal, a visita do Governador, as intrigas, o crime em Fortaleza e o enredo que se renova a cada cap\u00edtulo, como se fosse uma breve narrativa que vai tecendo n\u00f3s de marinheiros.<br \/>\nPor \u00faltimo, este livro \u00e9 prova ratificada de cearensidade, mar de escava\u00e7\u00e3o existencial, praia cheia de simplicidade, entrela\u00e7amento e areias onde dramas, percal\u00e7os e alegrias se encontram.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\ncronista<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 09\/04\/2006.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3577","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3577"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3577\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}