{"id":3638,"date":"2023-12-21T09:10:50","date_gmt":"2023-12-21T12:10:50","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/nelida-pinon-duas-palavras\/"},"modified":"2023-12-21T09:10:50","modified_gmt":"2023-12-21T12:10:50","slug":"nelida-pinon-duas-palavras","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/nelida-pinon-duas-palavras\/","title":{"rendered":"N\u00c9LIDA PI\u00d1ON: DUAS PALAVRAS"},"content":{"rendered":"<p>Na semana que passou, a escritora N\u00e9lida Pin\u00f5n visitou a Academia Fortalezense de Letras. Coube a mim a tarefa de saud\u00e1-la e \u00b4dizer duas palavras\u00b4. As duas palavras seriam: N\u00e9lida Pin\u00f5n. Bastaria isso. Procurei, todavia, fazer apenas algumas r\u00e1pidas observa\u00e7\u00f5es sobre essa ilustre visitante. Ei-las: N\u00e9lida \u00e9 um nome novo que com ela nasceu e que veio a existir pela criatividade de seu pai, Lino. N\u00e9lida \u00e9 uma anagrama de Daniel, seu av\u00f4 materno. Pi\u00f1on significa um pinh\u00e3o ou descanso de gatilho. Pinh\u00e3o \u00e9 uma engrenagem que se mexe, movimenta e gira. N\u00e9lida tem sido essa engrenagem na literatura brasileira. Professora de Cria\u00e7\u00e3o Liter\u00e1ria na UFRJ, romancista e contista, saiu de Vila Isabel, no Rio, e foi para a Gal\u00edcia de seus pais dos 10 aos 12 anos. Voltou e aqui sedimentou a sua forma\u00e7\u00e3o. A partir da\u00ed virou cidad\u00e3 letrada do mundo, descansando o seu gatilho ou mexendo as suas engrenagens do saber na City University of New York, Columbia University, Miami University, John Hopkins University, Universidad Cat\u00f3lica de Lima e na Universidad Complutense de Madrid.<br \/>\nSuas engrenagens liter\u00e1rias continuaram a girar. Dessa vez em dire\u00e7\u00e3o aos dicion\u00e1rios e \u00e0 imortalidade.Pois foi ela, em 1990, a sucessora de ningu\u00e9m menos que Aur\u00e9lio Buarque de Holanda na Academia Brasileira de Letras e, em 1996, substituiu a Ant\u00f4nio Houaiss na Presid\u00eancia da ABL. Era a primeira mulher &#8211; e \u00fanica at\u00e9 hoje &#8211; a ser presidente da Academia Brasileira de Letras. Uma mulher de letras, cercada por muitos fard\u00f5es, guardada ou guardando Aur\u00e9lio e o Houaiss, os fil\u00f3logos e os dicion\u00e1rios.<br \/>\nA obra de N\u00e9lida \u00e9 vasta. N\u00e3o cabe analis\u00e1-la neste arremedo de apresenta\u00e7\u00e3o. Mas recomendaria, entre tantos romances e contos, pelo menos um breve conto: I love my husband. Nesse conto, N\u00e9lida vai quase nocauteando o leitor, mas o deixa consciente para a reflex\u00e3o sobre o viver a dois nesta terra brasilis, ainda t\u00e3o machista.<br \/>\nA nossa ilustre convidada \u00e9 mulher de muita premia\u00e7\u00e3o. Em 1995, entre outros, ganhou o Pr\u00eamio Internacional de Literatura Juan Rulfo, da Universidad de Guadalajara, no M\u00e9xico. Antes, j\u00e1 havia ganhado os pr\u00eamios nacionais Walmap, M\u00e1rio de Andrade, Pen Clube, Bienal Nestl\u00e9, Golfinho de Ouro e outros.<br \/>\nEm seus romances (Guia-mapa de Miguel Arcanjo, Madeira feita cruz, Fundador, A Casa da Paix\u00e3o, Tebas do meu cora\u00e7\u00e3o, A Rep\u00fablica dos sonhos, A doce can\u00e7\u00e3o de Caetana, Vozes do Deserto etc) e contos ( Tempos das frutas, Sala de armas, O calor das coisas etc), N\u00e9lida deixa flagrante a sua rara habilidade em tratar dos mist\u00e9rios, dilemas e ang\u00fastias do fazer liter\u00e1rio, e isso parece incomodar aos que n\u00e3o sabem que a gl\u00f3ria de quem escreve \u00e9 ser bem lido por seu povo, tornando-o mais reflexivo e consciente das dores e amores do mundo. N\u00e9lida faz isso e os seus leitores sabem disso h\u00e1 mais de quarenta anos. Fique bem-vinda, sempre.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 30\/01\/2005<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na semana que passou, a escritora N\u00e9lida Pin\u00f5n visitou a Academia Fortalezense de Letras. Coube a mim a tarefa de saud\u00e1-la e \u00b4dizer duas palavras\u00b4. As duas palavras seriam: N\u00e9lida Pin\u00f5n. Bastaria isso. Procurei, todavia, fazer apenas algumas r\u00e1pidas observa\u00e7\u00f5es sobre essa ilustre visitante. Ei-las: N\u00e9lida \u00e9 um nome novo que com ela nasceu e que veio a existir pela criatividade de seu pai, Lino. N\u00e9lida \u00e9 uma anagrama de Daniel, seu av\u00f4 materno. Pi\u00f1on significa um pinh\u00e3o ou descanso de gatilho. Pinh\u00e3o \u00e9 uma engrenagem que se mexe, movimenta e gira. N\u00e9lida tem sido essa engrenagem na literatura brasileira. Professora de Cria\u00e7\u00e3o Liter\u00e1ria na UFRJ, romancista e contista, saiu de Vila Isabel, no Rio, e foi para a Gal\u00edcia de seus pais dos 10 aos 12 anos. Voltou e aqui sedimentou a sua forma\u00e7\u00e3o. A partir da\u00ed virou cidad\u00e3 letrada do mundo, descansando o seu gatilho ou mexendo as suas engrenagens do saber na City University of New York, Columbia University, Miami University, John Hopkins University, Universidad Cat\u00f3lica de Lima e na Universidad Complutense de Madrid.<br \/>\nSuas engrenagens liter\u00e1rias continuaram a girar. Dessa vez em dire\u00e7\u00e3o aos dicion\u00e1rios e \u00e0 imortalidade.Pois foi ela, em 1990, a sucessora de ningu\u00e9m menos que Aur\u00e9lio Buarque de Holanda na Academia Brasileira de Letras e, em 1996, substituiu a Ant\u00f4nio Houaiss na Presid\u00eancia da ABL. Era a primeira mulher &#8211; e \u00fanica at\u00e9 hoje &#8211; a ser presidente da Academia Brasileira de Letras. Uma mulher de letras, cercada por muitos fard\u00f5es, guardada ou guardando Aur\u00e9lio e o Houaiss, os fil\u00f3logos e os dicion\u00e1rios.<br \/>\nA obra de N\u00e9lida \u00e9 vasta. N\u00e3o cabe analis\u00e1-la neste arremedo de apresenta\u00e7\u00e3o. Mas recomendaria, entre tantos romances e contos, pelo menos um breve conto: I love my husband. Nesse conto, N\u00e9lida vai quase nocauteando o leitor, mas o deixa consciente para a reflex\u00e3o sobre o viver a dois nesta terra brasilis, ainda t\u00e3o machista.<br \/>\nA nossa ilustre convidada \u00e9 mulher de muita premia\u00e7\u00e3o. Em 1995, entre outros, ganhou o Pr\u00eamio Internacional de Literatura Juan Rulfo, da Universidad de Guadalajara, no M\u00e9xico. Antes, j\u00e1 havia ganhado os pr\u00eamios nacionais Walmap, M\u00e1rio de Andrade, Pen Clube, Bienal Nestl\u00e9, Golfinho de Ouro e outros.<br \/>\nEm seus romances (Guia-mapa de Miguel Arcanjo, Madeira feita cruz, Fundador, A Casa da Paix\u00e3o, Tebas do meu cora\u00e7\u00e3o, A Rep\u00fablica dos sonhos, A doce can\u00e7\u00e3o de Caetana, Vozes do Deserto etc) e contos ( Tempos das frutas, Sala de armas, O calor das coisas etc), N\u00e9lida deixa flagrante a sua rara habilidade em tratar dos mist\u00e9rios, dilemas e ang\u00fastias do fazer liter\u00e1rio, e isso parece incomodar aos que n\u00e3o sabem que a gl\u00f3ria de quem escreve \u00e9 ser bem lido por seu povo, tornando-o mais reflexivo e consciente das dores e amores do mundo. N\u00e9lida faz isso e os seus leitores sabem disso h\u00e1 mais de quarenta anos. Fique bem-vinda, sempre.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 30\/01\/2005<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3638","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3638"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3638\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}