{"id":3676,"date":"2023-12-21T09:10:51","date_gmt":"2023-12-21T12:10:51","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/liberdade-igualdade-e-oportunidade\/"},"modified":"2023-12-21T09:10:51","modified_gmt":"2023-12-21T12:10:51","slug":"liberdade-igualdade-e-oportunidade","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/liberdade-igualdade-e-oportunidade\/","title":{"rendered":"LIBERDADE, IGUALDADE E OPORTUNIDADE"},"content":{"rendered":"<p>H\u00e1 pouco tempo passei a virada do ano em Paris. Fazia frio, n\u00e3o havia t\u00e1xis nas ruas e os metr\u00f4s estavam superlotados, porque gratuitos naquele dia. Depois do jantar, resolvi dar uma caminhada na regi\u00e3o de Trocad\u00e9ro, onde fica a Torre Eiffel. \u00c9 um grande parque, lindamente gramado, fontes jorrando, bem iluminado, pr\u00f3xima do Rio Sena e da ponte D\u2019I\u00e9da.<br \/>\nDesci as escadarias. Havia muita gente, especialmente fam\u00edlias, mas notei que poucos pareciam franceses ou, pelo menos, o que imaginava ainda pudesse ser o bi\u00f3tipo do franc\u00eas. Ningu\u00e9m parecido com Alain Delon, Jacques Chirac, Jean Paul Belmondo e afins. Havia gente parecida com Zidane e com os muitos franceses -ou n\u00e3o- oriundos das col\u00f4nias africanas. Havia muitos \u00e1rabes ou filhos de \u00e1rabes. O leito do Sena estava sujo de garrafas vazias, camel\u00f4s vendiam quinquilharias luminosas e a algaravia de idiomas me deixava desconcertado.<br \/>\nO meu olhar procurara um t\u00e1xi salvador, pois j\u00e1 viera de metr\u00f4. Era a primeira hora dia do novo ano e eu em meio \u00e0 turba que cantava, bebia, vendia, enquanto outros, j\u00e1 entregues ao cansa\u00e7o, dormiam sobre a relva. Naquele instante, passou o filme de minha primeira visita \u00e0 Fran\u00e7a, em 1965. Era outro o pa\u00eds, n\u00e3o sei se melhor ou pior, mas o povo parecia ter uma maior identidade com a sua hist\u00f3ria. Ali, naquela madrugada, eu via algo como uma ocupa\u00e7\u00e3o de imigrantes ou de seus filhos que tentavam se amalgamar aos costumes franceses, mas pareciam estranhos \u00e0 terra, embora essa fosse deles.<br \/>\nTudo isso me voltou \u00e0 mente ao acompanhar o que est\u00e1 acontecendo nestes dias na Fran\u00e7a. Milhares de carros s\u00e3o queimados nas vias p\u00fablicas e a imprensa destaca que os inc\u00eandios s\u00e3o provocados por jovens negros e de origem \u00e1rabe, todos na faixa de 20 anos, que reclamam de discrimina\u00e7\u00e3o no mercado de trabalho, poucas oportunidades de empregos e sentimento de marginaliza\u00e7\u00e3o social. Esse caos, que j\u00e1 se espalha pela Europa, \u00e9 o retrato de um mundo desigual que teima em n\u00e3o ver a realidade, t\u00e3o dura quanto pr\u00f3xima da vida de todos. O premi\u00ea franc\u00eas, Dominique de Villepin, meio perplexo, diz que \u00e9 preciso respeitar a todos e cada um pelo que s\u00e3o, mas, ao mesmo tempo, destaca que os atos de viol\u00eancia s\u00e3o \u201cinaceit\u00e1veis e indesculp\u00e1veis\u201d. E a Europa passa a viver o rescaldo da imigra\u00e7\u00e3o, talvez uma resposta tardia \u00e0 coloniza\u00e7\u00e3o que pode ter originado esse drama cujo primeiro ato estamos vendo. <\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\ncronista<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 13\/11\/2005.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 pouco tempo passei a virada do ano em Paris. Fazia frio, n\u00e3o havia t\u00e1xis nas ruas e os metr\u00f4s estavam superlotados, porque gratuitos naquele dia. Depois do jantar, resolvi dar uma caminhada na regi\u00e3o de Trocad\u00e9ro, onde fica a Torre Eiffel. \u00c9 um grande parque, lindamente gramado, fontes jorrando, bem iluminado, pr\u00f3xima do Rio Sena e da ponte D\u2019I\u00e9da.<br \/>\nDesci as escadarias. Havia muita gente, especialmente fam\u00edlias, mas notei que poucos pareciam franceses ou, pelo menos, o que imaginava ainda pudesse ser o bi\u00f3tipo do franc\u00eas. Ningu\u00e9m parecido com Alain Delon, Jacques Chirac, Jean Paul Belmondo e afins. Havia gente parecida com Zidane e com os muitos franceses -ou n\u00e3o- oriundos das col\u00f4nias africanas. Havia muitos \u00e1rabes ou filhos de \u00e1rabes. O leito do Sena estava sujo de garrafas vazias, camel\u00f4s vendiam quinquilharias luminosas e a algaravia de idiomas me deixava desconcertado.<br \/>\nO meu olhar procurara um t\u00e1xi salvador, pois j\u00e1 viera de metr\u00f4. Era a primeira hora dia do novo ano e eu em meio \u00e0 turba que cantava, bebia, vendia, enquanto outros, j\u00e1 entregues ao cansa\u00e7o, dormiam sobre a relva. Naquele instante, passou o filme de minha primeira visita \u00e0 Fran\u00e7a, em 1965. Era outro o pa\u00eds, n\u00e3o sei se melhor ou pior, mas o povo parecia ter uma maior identidade com a sua hist\u00f3ria. Ali, naquela madrugada, eu via algo como uma ocupa\u00e7\u00e3o de imigrantes ou de seus filhos que tentavam se amalgamar aos costumes franceses, mas pareciam estranhos \u00e0 terra, embora essa fosse deles.<br \/>\nTudo isso me voltou \u00e0 mente ao acompanhar o que est\u00e1 acontecendo nestes dias na Fran\u00e7a. Milhares de carros s\u00e3o queimados nas vias p\u00fablicas e a imprensa destaca que os inc\u00eandios s\u00e3o provocados por jovens negros e de origem \u00e1rabe, todos na faixa de 20 anos, que reclamam de discrimina\u00e7\u00e3o no mercado de trabalho, poucas oportunidades de empregos e sentimento de marginaliza\u00e7\u00e3o social. Esse caos, que j\u00e1 se espalha pela Europa, \u00e9 o retrato de um mundo desigual que teima em n\u00e3o ver a realidade, t\u00e3o dura quanto pr\u00f3xima da vida de todos. O premi\u00ea franc\u00eas, Dominique de Villepin, meio perplexo, diz que \u00e9 preciso respeitar a todos e cada um pelo que s\u00e3o, mas, ao mesmo tempo, destaca que os atos de viol\u00eancia s\u00e3o \u201cinaceit\u00e1veis e indesculp\u00e1veis\u201d. E a Europa passa a viver o rescaldo da imigra\u00e7\u00e3o, talvez uma resposta tardia \u00e0 coloniza\u00e7\u00e3o que pode ter originado esse drama cujo primeiro ato estamos vendo. <\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\ncronista<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 13\/11\/2005.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3676","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3676"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3676\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}