{"id":3684,"date":"2023-12-21T09:10:51","date_gmt":"2023-12-21T12:10:51","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/o-ze-do-campanario\/"},"modified":"2023-12-21T09:10:51","modified_gmt":"2023-12-21T12:10:51","slug":"o-ze-do-campanario","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/o-ze-do-campanario\/","title":{"rendered":"O Z\u00c9 DO CAMPAN\u00c1RIO"},"content":{"rendered":"<p>Audifax Rios galopa com maestria pelas areias da cidade imagin\u00e1ria ou imaginada de Campan\u00e1rio. Desloca-se na garra de um homem novo pela floresta adentro e o traz de volta com muito ouro e disposi\u00e7\u00e3o. Tudo para dar sentido, vida, sustan\u00e7a e destino a Z\u00e9 do Egito ou Zegito.<br \/>\nDetalha com cinzel de artes\u00e3o, pincel naife, linguajar de escritor maduro, prosa livre de cantador sem viola e a propriedade de etn\u00f3grafo, o que vai ocorrendo na vida e nas circunst\u00e2ncias do Zegito. Como se fora um ferrador de gado, vai marcando, vezes sem conta, o que passa na mente e nos possu\u00eddos desse matuto brabo nascido no ano de 191. E o tr\u00e1s pelo cabresto, ao final desenfreado, at\u00e9 os recentes idos de 1964. H\u00e1 tanta beleza na narrativa de Audifax que \u00e9 dif\u00edcil pin\u00e7ar trechos, sem cometer injusti\u00e7a, trechos entre os que embevecem, prendem e seduzem o leitor. Apenas dois exemplos:<br \/>\nUm: \u00b4Pois eu lhe conto uns tantos e quantos sucessos das gentes deste lugar perdido nos cafund\u00f3s do sert\u00e3o nordestino, que bem poderia ser um qualquer outro peda\u00e7o esquecido do planeta. Conversa fiada sobre alguns viventes de um ch\u00e3o aben\u00e7oado e maldito, empoeirado pelo arrastado das bestas-feras e burras-de padre povoantes destes pagos em noite de espanto.<br \/>\nDois: \u00b4E durante este tr\u00edduo de chuvas nefastas continuaram a desabar raios de pouca monta em compara\u00e7\u00e3o com a bola gigantesca e queimaram-se todos os bicos de luz, as v\u00e1lvulas dos r\u00e1dios rabos-quentes e seus esmeraldos olhos m\u00e1gicos. Engui\u00e7aram tamb\u00e9m os aparelhos alto-falantes e o Morse do tel\u00e9grafo e tudo quanto dependia de magnetos e galenas e outras maravilhas da ci\u00eancia el\u00e9trica e mais descobertas deslumbrantes naqueles tempos de progresso.<br \/>\nCom o jeito de quem conhece a estrada onde pisou e\u00b4as gentes deste lugar perdido\u00b4, Audifax Rios vai tecendo as teias do tecido social de uma cidade que recebe, em 1946, Zegito em seu retorno de her\u00f3i-bandido das terras molhadas do Amazonas. Alforje pleno de ouro, um curumim-filho a tiracolo e uma disposi\u00e7\u00e3o imensa de mostrar a todos quem era e quem seria, chega e finca os seus mour\u00f5es, o dito Jos\u00e9 do Egito. De sobrenome t\u00e3o grande quanto desnecess\u00e1rio, pois a fama da\u00ed para frente constru\u00edda \u00e9 fruto do Zegito, um agitador que tinha as r\u00e9deas da cidade e o benepl\u00e1cito do c\u00e9u pela intercess\u00e3o do Pe.Justiniano, que acumulava as fun\u00e7\u00f5es de seu amigo, confidente, s\u00f3cio e benefici\u00e1rio das suas diatribes.<br \/>\nS\u00e3o tantos os personagens fortes ou sutis, marcantes ou marcados desta mini-epop\u00e9ia que me indago a raz\u00e3o do destaque aos b\u00fafalos que, nada fizeram al\u00e9m de um galope alucinado igreja a dentro e da beberagem tomada pelos irracionais e racionais, todos animais, explodindo a capacidade \u00b4viagr\u00e1tica\u00b4 de uma procria\u00e7\u00e3o maltusiana que nos faz lembrar o melhor da fant\u00e1stica cria\u00e7\u00e3o dos escritores latinos de l\u00edngua hisp\u00e2nica.<\/p>\n<p>N\u00e3o \u00e9 preciso sair citando, um a um, os coadjuvantes dessa cidade-circo mambembe que nos lembra as reina\u00e7\u00f5es de Ariano Suassuna e, longe, muito longe, a fase primeira de Jorge Amado, nos confins das terras dos cacaus.<br \/>\nT\u00e3o rico \u00e9 Zegito que o aposto- \u00e9 aposto mesmo &#8211; de Major \u00e9 sup\u00e9rfluo e descabido. Essa patente teria sido \u00b4comprada a peso de ouro \u00e0 Guarda Nacional\u00b4, entidade extinta pelo presidente Wenceslau Br\u00e1s desde 1918 e, por tal raz\u00e3o, desconectada da cronologia da narrativa. Tal fato, sem macular o brilho da hist\u00f3ria, d\u00e1 a Audifax o cond\u00e3o que tem os autores de mexerem com a temporalidade, sem que isso perturbe ou aflija quem l\u00ea este livro.<br \/>\nOra, Candinha, Orapronobias, , Padre Justiniano, Henrique Imagin\u00e1rio, Maria Guayana, Messias Salvador e muitos outros s\u00e3o mais relevantes e revelantes que os 12 b\u00fafalos trazidos da Ilha de Maraj\u00f3 e que, incontidos em sua sexualidade, transgrediram as leis da natureza e receberam, quem sabe, por castigo a morte coletiva \u00b4\u00e0 beira do abismo inacabado\u00b4.<br \/>\nCada um desses coadjuvantes marca com \u00b4letras capitulares\u00b4 todo o enredo que conta a saga, com um fim aligeirado, e a volta-fuga n\u00e3o bem explicada de Zegito para a Amaz\u00f4nia. Por estas e por outras n\u00e3o contadas \u00e9 que me rendo ao t\u00edtulo marquetado de \u00b4Os B\u00fafalos de Campan\u00e1rio\u00b4, mas faria, igualmente, elogios ao brilhante Audifax se \u00b4O Z\u00e9 do Campan\u00e1rio\u00b4 estivesse incrustado no frontisp\u00edcio deste primoroso livro que fecha com fulgor o ano da gra\u00e7a de 2003, t\u00e3o rico em surpresa, quanto em desencanto, mas que prenuncia alv\u00edssaras para todos no raiar do 2004. Os b\u00fafalos, afinal, j\u00e1 se foram.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nescritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 11\/01\/2004.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Audifax Rios galopa com maestria pelas areias da cidade imagin\u00e1ria ou imaginada de Campan\u00e1rio. Desloca-se na garra de um homem novo pela floresta adentro e o traz de volta com muito ouro e disposi\u00e7\u00e3o. Tudo para dar sentido, vida, sustan\u00e7a e destino a Z\u00e9 do Egito ou Zegito.<br \/>\nDetalha com cinzel de artes\u00e3o, pincel naife, linguajar de escritor maduro, prosa livre de cantador sem viola e a propriedade de etn\u00f3grafo, o que vai ocorrendo na vida e nas circunst\u00e2ncias do Zegito. Como se fora um ferrador de gado, vai marcando, vezes sem conta, o que passa na mente e nos possu\u00eddos desse matuto brabo nascido no ano de 191. E o tr\u00e1s pelo cabresto, ao final desenfreado, at\u00e9 os recentes idos de 1964. H\u00e1 tanta beleza na narrativa de Audifax que \u00e9 dif\u00edcil pin\u00e7ar trechos, sem cometer injusti\u00e7a, trechos entre os que embevecem, prendem e seduzem o leitor. Apenas dois exemplos:<br \/>\nUm: \u00b4Pois eu lhe conto uns tantos e quantos sucessos das gentes deste lugar perdido nos cafund\u00f3s do sert\u00e3o nordestino, que bem poderia ser um qualquer outro peda\u00e7o esquecido do planeta. Conversa fiada sobre alguns viventes de um ch\u00e3o aben\u00e7oado e maldito, empoeirado pelo arrastado das bestas-feras e burras-de padre povoantes destes pagos em noite de espanto.<br \/>\nDois: \u00b4E durante este tr\u00edduo de chuvas nefastas continuaram a desabar raios de pouca monta em compara\u00e7\u00e3o com a bola gigantesca e queimaram-se todos os bicos de luz, as v\u00e1lvulas dos r\u00e1dios rabos-quentes e seus esmeraldos olhos m\u00e1gicos. Engui\u00e7aram tamb\u00e9m os aparelhos alto-falantes e o Morse do tel\u00e9grafo e tudo quanto dependia de magnetos e galenas e outras maravilhas da ci\u00eancia el\u00e9trica e mais descobertas deslumbrantes naqueles tempos de progresso.<br \/>\nCom o jeito de quem conhece a estrada onde pisou e\u00b4as gentes deste lugar perdido\u00b4, Audifax Rios vai tecendo as teias do tecido social de uma cidade que recebe, em 1946, Zegito em seu retorno de her\u00f3i-bandido das terras molhadas do Amazonas. Alforje pleno de ouro, um curumim-filho a tiracolo e uma disposi\u00e7\u00e3o imensa de mostrar a todos quem era e quem seria, chega e finca os seus mour\u00f5es, o dito Jos\u00e9 do Egito. De sobrenome t\u00e3o grande quanto desnecess\u00e1rio, pois a fama da\u00ed para frente constru\u00edda \u00e9 fruto do Zegito, um agitador que tinha as r\u00e9deas da cidade e o benepl\u00e1cito do c\u00e9u pela intercess\u00e3o do Pe.Justiniano, que acumulava as fun\u00e7\u00f5es de seu amigo, confidente, s\u00f3cio e benefici\u00e1rio das suas diatribes.<br \/>\nS\u00e3o tantos os personagens fortes ou sutis, marcantes ou marcados desta mini-epop\u00e9ia que me indago a raz\u00e3o do destaque aos b\u00fafalos que, nada fizeram al\u00e9m de um galope alucinado igreja a dentro e da beberagem tomada pelos irracionais e racionais, todos animais, explodindo a capacidade \u00b4viagr\u00e1tica\u00b4 de uma procria\u00e7\u00e3o maltusiana que nos faz lembrar o melhor da fant\u00e1stica cria\u00e7\u00e3o dos escritores latinos de l\u00edngua hisp\u00e2nica.<\/p>\n<p>N\u00e3o \u00e9 preciso sair citando, um a um, os coadjuvantes dessa cidade-circo mambembe que nos lembra as reina\u00e7\u00f5es de Ariano Suassuna e, longe, muito longe, a fase primeira de Jorge Amado, nos confins das terras dos cacaus.<br \/>\nT\u00e3o rico \u00e9 Zegito que o aposto- \u00e9 aposto mesmo &#8211; de Major \u00e9 sup\u00e9rfluo e descabido. Essa patente teria sido \u00b4comprada a peso de ouro \u00e0 Guarda Nacional\u00b4, entidade extinta pelo presidente Wenceslau Br\u00e1s desde 1918 e, por tal raz\u00e3o, desconectada da cronologia da narrativa. Tal fato, sem macular o brilho da hist\u00f3ria, d\u00e1 a Audifax o cond\u00e3o que tem os autores de mexerem com a temporalidade, sem que isso perturbe ou aflija quem l\u00ea este livro.<br \/>\nOra, Candinha, Orapronobias, , Padre Justiniano, Henrique Imagin\u00e1rio, Maria Guayana, Messias Salvador e muitos outros s\u00e3o mais relevantes e revelantes que os 12 b\u00fafalos trazidos da Ilha de Maraj\u00f3 e que, incontidos em sua sexualidade, transgrediram as leis da natureza e receberam, quem sabe, por castigo a morte coletiva \u00b4\u00e0 beira do abismo inacabado\u00b4.<br \/>\nCada um desses coadjuvantes marca com \u00b4letras capitulares\u00b4 todo o enredo que conta a saga, com um fim aligeirado, e a volta-fuga n\u00e3o bem explicada de Zegito para a Amaz\u00f4nia. Por estas e por outras n\u00e3o contadas \u00e9 que me rendo ao t\u00edtulo marquetado de \u00b4Os B\u00fafalos de Campan\u00e1rio\u00b4, mas faria, igualmente, elogios ao brilhante Audifax se \u00b4O Z\u00e9 do Campan\u00e1rio\u00b4 estivesse incrustado no frontisp\u00edcio deste primoroso livro que fecha com fulgor o ano da gra\u00e7a de 2003, t\u00e3o rico em surpresa, quanto em desencanto, mas que prenuncia alv\u00edssaras para todos no raiar do 2004. Os b\u00fafalos, afinal, j\u00e1 se foram.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nescritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 11\/01\/2004.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3684","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3684"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3684\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}