{"id":3700,"date":"2023-12-21T09:10:52","date_gmt":"2023-12-21T12:10:52","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/o-amor-atual\/"},"modified":"2023-12-21T09:10:52","modified_gmt":"2023-12-21T12:10:52","slug":"o-amor-atual","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/o-amor-atual\/","title":{"rendered":"O AMOR ATUAL"},"content":{"rendered":"<p>Somos todos frutos do amor. Seja ele duradouro ou circunstancial. De uma forma ou de outra, temos uma fam\u00edlia que nos insere no mundo. Um dia, deixamos de ser filhos, e passamos a ver o amor como a mais leg\u00edtima forma de estabelecer novos la\u00e7os afetivos. A partir desse dia, vemos que \u00e9 preciso encontrar uma pessoa a quem possamos amar, atrav\u00e9s de um processo de aproxima\u00e7\u00e3o sucessiva, manter essa rela\u00e7\u00e3o atraente, n\u00e3o desgastante-sufocante e viva com o correr do tempo, seja curto ou longo. E ao lado do amor, deixar fluir a vida real.<br \/>\nVivemos, quer queiramos ou n\u00e3o, o tempo da p\u00f3s-modernidade, essa coisa meio chata de definir, mas que pode ser encarada de v\u00e1rios \u00e2ngulos e aspectos. Por sermos humanos, n\u00e3o temos selos de garantia, somos fracos e falhos. E temos urg\u00eancia em viver relacionamentos que nos deem prazer, apoio e danifiquem o menos poss\u00edvel os nossos sentimentos. Al\u00e9m de tudo isso, como vivemos contextualizados, n\u00e3o podemos fugir muito das regras sociais da fam\u00edlia, grupo e local. Somos comparados e comparamos. Temos que crescer profissionalmente, tamb\u00e9m. \u201cIsto \u00e9 b\u00e1sico\u201d, na linguagem atual.<br \/>\nEsse mundo p\u00f3s-moderno (do computador, celular, emprego externo ou em casa, contas divididas, inseguran\u00e7a pessoal e coletiva, caixa eletr\u00f4nico, carro, liberdade, viagras e horm\u00f4nios, corpos malhados ou remodelados querendo parar o tempo, mot\u00e9is e da fragilidade dos relacionamentos) fez o ser humano ficar ainda mais t\u00edmido e confuso, admitindo que o seu amor pode se esvair rapidamente.<br \/>\nHoje, al\u00e9m de todas as artimanhas do amor, os casais t\u00eam que formar uma s\u00f3lida base econ\u00f4mico-financeira que os proteja da volatilidade dos empregos e da incerteza do futuro que \u00e9 a \u00fanica certeza.<br \/>\nPor tudo isso \u00e9 que j\u00e1 n\u00e3o se estranha que uma pessoa entre em um relacionamento sem encerrar as contas do anterior, de modo a descobrir no outro o que falta \u201cnaquele, de antes\u201d. Se der certo, fecha as contas de um e abre outra. H\u00e1, ainda, as categorias de casados-mornos ou casados-(a)parentes. Nelas, os parceiros t\u00eam consci\u00eancia do desgaste da rela\u00e7\u00e3o, esperam que os filhos cres\u00e7am ou que o tempo fa\u00e7a um milagre.<br \/>\nOs amores, at\u00e9 em casas separadas, e n\u00e3o mais apenas em quartos separados, s\u00e3o ind\u00edcios da fragilidade da consist\u00eancia afetiva entre as pessoas. Por outro lado, a liberdade atingida permite ainda a troca continua de parceiros, o que banaliza o relacionamento. Ficar com algu\u00e9m \u00e9 distinto de amar algu\u00e9m. Sair para ver o que vai dar \u00e9 diferente daquela busca rom\u00e2ntica e finita do outro. O verdadeiro encontro ou prazer s\u00f3 se d\u00e1 com o amor. O tempo n\u00e3o \u00e9 santo, pois \u00e9 contaminado pelo dia-a-dia da vida crua e nua, que vemos dentro e fora de nossas janelas. O resto \u00e9 ato.<br \/>\nJo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 22\/08\/2004.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Somos todos frutos do amor. Seja ele duradouro ou circunstancial. De uma forma ou de outra, temos uma fam\u00edlia que nos insere no mundo. Um dia, deixamos de ser filhos, e passamos a ver o amor como a mais leg\u00edtima forma de estabelecer novos la\u00e7os afetivos. A partir desse dia, vemos que \u00e9 preciso encontrar uma pessoa a quem possamos amar, atrav\u00e9s de um processo de aproxima\u00e7\u00e3o sucessiva, manter essa rela\u00e7\u00e3o atraente, n\u00e3o desgastante-sufocante e viva com o correr do tempo, seja curto ou longo. E ao lado do amor, deixar fluir a vida real.<br \/>\nVivemos, quer queiramos ou n\u00e3o, o tempo da p\u00f3s-modernidade, essa coisa meio chata de definir, mas que pode ser encarada de v\u00e1rios \u00e2ngulos e aspectos. Por sermos humanos, n\u00e3o temos selos de garantia, somos fracos e falhos. E temos urg\u00eancia em viver relacionamentos que nos deem prazer, apoio e danifiquem o menos poss\u00edvel os nossos sentimentos. Al\u00e9m de tudo isso, como vivemos contextualizados, n\u00e3o podemos fugir muito das regras sociais da fam\u00edlia, grupo e local. Somos comparados e comparamos. Temos que crescer profissionalmente, tamb\u00e9m. \u201cIsto \u00e9 b\u00e1sico\u201d, na linguagem atual.<br \/>\nEsse mundo p\u00f3s-moderno (do computador, celular, emprego externo ou em casa, contas divididas, inseguran\u00e7a pessoal e coletiva, caixa eletr\u00f4nico, carro, liberdade, viagras e horm\u00f4nios, corpos malhados ou remodelados querendo parar o tempo, mot\u00e9is e da fragilidade dos relacionamentos) fez o ser humano ficar ainda mais t\u00edmido e confuso, admitindo que o seu amor pode se esvair rapidamente.<br \/>\nHoje, al\u00e9m de todas as artimanhas do amor, os casais t\u00eam que formar uma s\u00f3lida base econ\u00f4mico-financeira que os proteja da volatilidade dos empregos e da incerteza do futuro que \u00e9 a \u00fanica certeza.<br \/>\nPor tudo isso \u00e9 que j\u00e1 n\u00e3o se estranha que uma pessoa entre em um relacionamento sem encerrar as contas do anterior, de modo a descobrir no outro o que falta \u201cnaquele, de antes\u201d. Se der certo, fecha as contas de um e abre outra. H\u00e1, ainda, as categorias de casados-mornos ou casados-(a)parentes. Nelas, os parceiros t\u00eam consci\u00eancia do desgaste da rela\u00e7\u00e3o, esperam que os filhos cres\u00e7am ou que o tempo fa\u00e7a um milagre.<br \/>\nOs amores, at\u00e9 em casas separadas, e n\u00e3o mais apenas em quartos separados, s\u00e3o ind\u00edcios da fragilidade da consist\u00eancia afetiva entre as pessoas. Por outro lado, a liberdade atingida permite ainda a troca continua de parceiros, o que banaliza o relacionamento. Ficar com algu\u00e9m \u00e9 distinto de amar algu\u00e9m. Sair para ver o que vai dar \u00e9 diferente daquela busca rom\u00e2ntica e finita do outro. O verdadeiro encontro ou prazer s\u00f3 se d\u00e1 com o amor. O tempo n\u00e3o \u00e9 santo, pois \u00e9 contaminado pelo dia-a-dia da vida crua e nua, que vemos dentro e fora de nossas janelas. O resto \u00e9 ato.<br \/>\nJo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 22\/08\/2004.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3700","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3700"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3700\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}