{"id":3719,"date":"2023-12-21T09:10:52","date_gmt":"2023-12-21T12:10:52","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/bushussein-o-show-da-vida-e-da-morte\/"},"modified":"2023-12-21T09:10:52","modified_gmt":"2023-12-21T12:10:52","slug":"bushussein-o-show-da-vida-e-da-morte","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/bushussein-o-show-da-vida-e-da-morte\/","title":{"rendered":"BUSHUSSEIN: O SHOW DA VIDA E DA MORTE"},"content":{"rendered":"<p>N\u00e3o quero ter na consci\u00eancia o peso da indiferen\u00e7a ou da omiss\u00e3o. Os canais de TV est\u00e3o fazendo da guerra do Golfo P\u00e9rsico um ato vil, s\u00e1dico, desumano e tornando as pessoas insens\u00edveis ao absurdo da agress\u00e3o m\u00fatua e da morte descabida. Pintar Saddam Hussein e George Bush de tiranos ou defensores ou o quer que seja, \u00e9 um filme t\u00e3o ultrapassado, de ret\u00f3rica antiga, consistente como um pudim e defens\u00e1vel como uma freira fazendo \u00b4strip-tease\u00b4.<br \/>\nNenhum analista pol\u00edtico americano ou iraquiano teve a coragem de ser expl\u00edcito: a guerra \u00e9 um emaranhado de mentiras, de embustes, de interesses econ\u00f4micos contrariados e a pretensa defesa ou conquista de um emirado do Oriente M\u00e9dio &#8211; que h\u00e1 pouco mais de trinta anos era parte de um protetorado brit\u00e2nico &#8211; n\u00e3o d\u00e1 a ningu\u00e9m o direito de fazer o que est\u00e1 sendo feito.<br \/>\nO Iraque brigou oito anos com o Ir\u00e3 e ningu\u00e9m se meteu. At\u00e9 armas qu\u00edmicas foram usadas. Os Estados Unidos invadiram Granada e o Panam\u00e1 e a ONU ficou calada. A R\u00fassia quase dizimou a Let\u00f4nia e nada. A Let\u00f4nia, o Panam\u00e1 e Granada n\u00e3o t\u00eam petr\u00f3leo. O Ir\u00e3 era inimigo dos Estados Unidos e o Iraque &#8211; at\u00e9 recentemente &#8211; seu aliado. Estes s\u00e3o os fatos. N\u00e3o consigo entender a raz\u00e3o pela qual os canais de TV, inclusive a poderosa CNN americana, se rendem &#8211; ou se vendem? &#8211; a um ilusionismo digno de Houdini. Esse canais s\u00e3o dirigidos por pessoas como n\u00f3s e se rendem a uma ign\u00f3bil propaganda, a mesma utilizada por Goebbels na Alemanha nazista. O elevado \u00edndice de aceita\u00e7\u00e3o (79%) por parte da opini\u00e3o p\u00fablica americana da posi\u00e7\u00e3o adotada por Bush e o gen. Collin Powell, o primeiro negro a comandar uma guerra nos Estados Unidos, reflete a maci\u00e7a propaganda mostrando que cabe aos Estados Unidos defender o mundo. Para defender o mundo, os Estados Unidos est\u00e3o com um contingente onde a maioria \u00e9 constitu\u00edda pelas minorias raciais. Basta dizer que, segundo o jornal New York Times de 25 de janeiro \u00faltimo, 24,6% do total de soldados \u00e9 de cor preta. Outro tanto \u00e9 constitu\u00eddo de latinos, eslavos, italianos etc. A parcela WASP (anglo-sax\u00f4nica, branca e protestante) \u00e9 menos que 50% do total de americanos envolvidos no conflito.<br \/>\nA humanidade sofre com a fome do terceiro mundo, onde a \u00c1frica e a Am\u00e9rica Latina s\u00e3o contrapontos na orgia de m\u00edsseis e tecnologias que devoram, por dia, a d\u00edvida externa da Bol\u00edvia. Os cientistas do primeiro mundo d\u00e3o uma demonstra\u00e7\u00e3o patente de aus\u00eancia de humanismo, de falta de preocupa\u00e7\u00e3o de males como a fome, o c\u00e2ncer, a Aids e as doen\u00e7as end\u00eamicas resultantes de atraso e do descaso de uma comunidade de seres privilegiados e alheados da realidade social.<br \/>\nNingu\u00e9m pode se orgulhar de uma guerra com data marcada, correspondentes a postos como se fosse uma olimp\u00edada, bilh\u00f5es de d\u00f3lares em equipamentos e em pessoal para serem dizimados em uma contabilidade onde o registro de uma fa\u00e7anha destruidora \u00e9 motivo de uma edi\u00e7\u00e3o extra por locutores com emo\u00e7\u00f5es org\u00e1sticas citando n\u00famero de mortos e feridos. Para concluir, s\u00f3 um detalhe: este artigo foi escrito e publicado neste Di\u00e1rio no dia 07 de fevereiro de 1991. Filme em reprise?<br \/>\nJo\u00e3o Soares Neto,<br \/>\nescritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 30\/03\/2003.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o quero ter na consci\u00eancia o peso da indiferen\u00e7a ou da omiss\u00e3o. Os canais de TV est\u00e3o fazendo da guerra do Golfo P\u00e9rsico um ato vil, s\u00e1dico, desumano e tornando as pessoas insens\u00edveis ao absurdo da agress\u00e3o m\u00fatua e da morte descabida. Pintar Saddam Hussein e George Bush de tiranos ou defensores ou o quer que seja, \u00e9 um filme t\u00e3o ultrapassado, de ret\u00f3rica antiga, consistente como um pudim e defens\u00e1vel como uma freira fazendo \u00b4strip-tease\u00b4.<br \/>\nNenhum analista pol\u00edtico americano ou iraquiano teve a coragem de ser expl\u00edcito: a guerra \u00e9 um emaranhado de mentiras, de embustes, de interesses econ\u00f4micos contrariados e a pretensa defesa ou conquista de um emirado do Oriente M\u00e9dio &#8211; que h\u00e1 pouco mais de trinta anos era parte de um protetorado brit\u00e2nico &#8211; n\u00e3o d\u00e1 a ningu\u00e9m o direito de fazer o que est\u00e1 sendo feito.<br \/>\nO Iraque brigou oito anos com o Ir\u00e3 e ningu\u00e9m se meteu. At\u00e9 armas qu\u00edmicas foram usadas. Os Estados Unidos invadiram Granada e o Panam\u00e1 e a ONU ficou calada. A R\u00fassia quase dizimou a Let\u00f4nia e nada. A Let\u00f4nia, o Panam\u00e1 e Granada n\u00e3o t\u00eam petr\u00f3leo. O Ir\u00e3 era inimigo dos Estados Unidos e o Iraque &#8211; at\u00e9 recentemente &#8211; seu aliado. Estes s\u00e3o os fatos. N\u00e3o consigo entender a raz\u00e3o pela qual os canais de TV, inclusive a poderosa CNN americana, se rendem &#8211; ou se vendem? &#8211; a um ilusionismo digno de Houdini. Esse canais s\u00e3o dirigidos por pessoas como n\u00f3s e se rendem a uma ign\u00f3bil propaganda, a mesma utilizada por Goebbels na Alemanha nazista. O elevado \u00edndice de aceita\u00e7\u00e3o (79%) por parte da opini\u00e3o p\u00fablica americana da posi\u00e7\u00e3o adotada por Bush e o gen. Collin Powell, o primeiro negro a comandar uma guerra nos Estados Unidos, reflete a maci\u00e7a propaganda mostrando que cabe aos Estados Unidos defender o mundo. Para defender o mundo, os Estados Unidos est\u00e3o com um contingente onde a maioria \u00e9 constitu\u00edda pelas minorias raciais. Basta dizer que, segundo o jornal New York Times de 25 de janeiro \u00faltimo, 24,6% do total de soldados \u00e9 de cor preta. Outro tanto \u00e9 constitu\u00eddo de latinos, eslavos, italianos etc. A parcela WASP (anglo-sax\u00f4nica, branca e protestante) \u00e9 menos que 50% do total de americanos envolvidos no conflito.<br \/>\nA humanidade sofre com a fome do terceiro mundo, onde a \u00c1frica e a Am\u00e9rica Latina s\u00e3o contrapontos na orgia de m\u00edsseis e tecnologias que devoram, por dia, a d\u00edvida externa da Bol\u00edvia. Os cientistas do primeiro mundo d\u00e3o uma demonstra\u00e7\u00e3o patente de aus\u00eancia de humanismo, de falta de preocupa\u00e7\u00e3o de males como a fome, o c\u00e2ncer, a Aids e as doen\u00e7as end\u00eamicas resultantes de atraso e do descaso de uma comunidade de seres privilegiados e alheados da realidade social.<br \/>\nNingu\u00e9m pode se orgulhar de uma guerra com data marcada, correspondentes a postos como se fosse uma olimp\u00edada, bilh\u00f5es de d\u00f3lares em equipamentos e em pessoal para serem dizimados em uma contabilidade onde o registro de uma fa\u00e7anha destruidora \u00e9 motivo de uma edi\u00e7\u00e3o extra por locutores com emo\u00e7\u00f5es org\u00e1sticas citando n\u00famero de mortos e feridos. Para concluir, s\u00f3 um detalhe: este artigo foi escrito e publicado neste Di\u00e1rio no dia 07 de fevereiro de 1991. Filme em reprise?<br \/>\nJo\u00e3o Soares Neto,<br \/>\nescritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 30\/03\/2003.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3719","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3719"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3719\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}