{"id":3720,"date":"2023-12-21T09:10:52","date_gmt":"2023-12-21T12:10:52","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/a-cidadania\/"},"modified":"2023-12-21T09:10:52","modified_gmt":"2023-12-21T12:10:52","slug":"a-cidadania","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/a-cidadania\/","title":{"rendered":"A CIDADANIA"},"content":{"rendered":"<p>Jos\u00e9 Guti\u00e9rrez nasceu em um bairro pobre da Guatemala. Viu que seria pobre eternamente e descobriu-se sonhando com um futuro mais promissor. N\u00e3o seria como seus pais, j\u00e1 velhos e sem perspectivas com menos de 50 anos. O mundo estava a\u00ed para ser conquistado. Trabalhou, juntou tudo o que tinha e fugiu para os Estados Unidos. Foi dar com os costados na Calif\u00f3rnia, lugar lindo, rico, em que tudo parecia funcionar. Viajava de trens, \u00f4nibus, caronas, mesmo que dormisse em pr\u00e9dios abandonados e vivesse se escondendo da \u201cla migra\u201d, como \u00e9 chamada a pol\u00edcia migrat\u00f3ria.<br \/>\nAcreditava haver encontrado um sentido para a sua vida e uma nova casa. N\u00e3o voltaria para a pobreza guatemalteca. Sonhava em ser um novo Antonio Banderas ou, quem sabe, um dono de uma daquelas lanchonetes em que a comida era cheirosa, serviam \u00e1gua com gelo e nos banheiros limpos fazia, escondido, os seus asseios.<br \/>\nUm dia, sem que esperasse, foi preso pela \u201cla migra\u201d. Desolado, soube por outros imigrantes ilegais que a melhor maneira de se safar era declarar-se refugiado. Assim o fez. Saiu das grades e viu que a \u00fanica sa\u00edda para ser igual aos outros que viviam na Am\u00e9rica era ter um \u201cstatus\u201d. Se n\u00e3o tinha dinheiro, n\u00e3o falava bem o ingl\u00eas, mas era forte e jovem, a solu\u00e7\u00e3o seria ingressar nas for\u00e7as armadas, onde j\u00e1 estavam 130 mil latinos como ele, e conseguir o \u201cgreen card\u201d.<br \/>\nEra vidrado em filmes de guerra em que os \u201cmarines\u201d sempre venciam as batalhas e tinham as mulheres que queriam. Seria um deles e mandaria fotos coloridas para seus pais e amigos da Guatemala. Escolheu o Corpo de Fuzileiros Navais. Agora era mais uma pra\u00e7a, o \u201cJoe\u201d.<br \/>\nVeio a oportunidade sonhada: a Guerra do Iraque. N\u00e3o sabia bem qual a raz\u00e3o dela, mas isso pouco importava. Teria viagens, bom soldo, promo\u00e7\u00f5es e gostaria de conhecer de perto aquelas mulheres que se cobriam todas. Tiraria os seus panos e mostraria porque se achava um Antonio Banderas.<br \/>\nViajou em um grande avi\u00e3o com farda camuflada e viu, ao chegar, que a coisa n\u00e3o era bem o que pensava. O Iraque lembrava a pobreza de sua Guatemala e o calor fazia ferver o seu sangue latino.Logo foi destacado para uma miss\u00e3o de reconhecimento em uma cidade que n\u00e3o sabia pronunciar o nome. Mascando chicletes, com toda uma parafern\u00e1lia de muni\u00e7\u00f5es, equipamentos e armas, pensava estar protagonizando um daqueles filmes em que os \u201cmarines\u201d sempre vencem. Seguia o que seu sargento mandava fazer e gostava de colocar os \u00f3culos em que via no escuro, como se fosse dia. Era, enfim um americano. O \u201cJoe\u201d. Em um instante, Jos\u00e9 Guti\u00e9rrez estava morto. Uma bala perdida ou dirigida, nunca se saber\u00e1, o encontrou. Era o segundo americano morto em opera\u00e7\u00f5es no Iraque. Nem a\u00ed teve a gl\u00f3ria de ser o primeiro. Seu corpo foi resgatado e colocado em um caix\u00e3o de zinco enrolado em uma bandeira americana. Voltou no por\u00e3o de um avi\u00e3o de guerra. A Am\u00e9rica concedeu a Jos\u00e9 Guti\u00e9rrez a cidadania post mortem, n\u00e3o precisaria mais do \u201cgreen card\u201d.<\/p>\n<p>Escrito por Jo\u00e3o Soares Neto, a partir de not\u00edcia ver\u00eddica do jornal \u201cEl Clar\u00edn\u201d, de Buenos Aires, edi\u00e7\u00e3o de 29.03.2003<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 13\/04\/2003.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Guti\u00e9rrez nasceu em um bairro pobre da Guatemala. Viu que seria pobre eternamente e descobriu-se sonhando com um futuro mais promissor. N\u00e3o seria como seus pais, j\u00e1 velhos e sem perspectivas com menos de 50 anos. O mundo estava a\u00ed para ser conquistado. Trabalhou, juntou tudo o que tinha e fugiu para os Estados Unidos. Foi dar com os costados na Calif\u00f3rnia, lugar lindo, rico, em que tudo parecia funcionar. Viajava de trens, \u00f4nibus, caronas, mesmo que dormisse em pr\u00e9dios abandonados e vivesse se escondendo da \u201cla migra\u201d, como \u00e9 chamada a pol\u00edcia migrat\u00f3ria.<br \/>\nAcreditava haver encontrado um sentido para a sua vida e uma nova casa. N\u00e3o voltaria para a pobreza guatemalteca. Sonhava em ser um novo Antonio Banderas ou, quem sabe, um dono de uma daquelas lanchonetes em que a comida era cheirosa, serviam \u00e1gua com gelo e nos banheiros limpos fazia, escondido, os seus asseios.<br \/>\nUm dia, sem que esperasse, foi preso pela \u201cla migra\u201d. Desolado, soube por outros imigrantes ilegais que a melhor maneira de se safar era declarar-se refugiado. Assim o fez. Saiu das grades e viu que a \u00fanica sa\u00edda para ser igual aos outros que viviam na Am\u00e9rica era ter um \u201cstatus\u201d. Se n\u00e3o tinha dinheiro, n\u00e3o falava bem o ingl\u00eas, mas era forte e jovem, a solu\u00e7\u00e3o seria ingressar nas for\u00e7as armadas, onde j\u00e1 estavam 130 mil latinos como ele, e conseguir o \u201cgreen card\u201d.<br \/>\nEra vidrado em filmes de guerra em que os \u201cmarines\u201d sempre venciam as batalhas e tinham as mulheres que queriam. Seria um deles e mandaria fotos coloridas para seus pais e amigos da Guatemala. Escolheu o Corpo de Fuzileiros Navais. Agora era mais uma pra\u00e7a, o \u201cJoe\u201d.<br \/>\nVeio a oportunidade sonhada: a Guerra do Iraque. N\u00e3o sabia bem qual a raz\u00e3o dela, mas isso pouco importava. Teria viagens, bom soldo, promo\u00e7\u00f5es e gostaria de conhecer de perto aquelas mulheres que se cobriam todas. Tiraria os seus panos e mostraria porque se achava um Antonio Banderas.<br \/>\nViajou em um grande avi\u00e3o com farda camuflada e viu, ao chegar, que a coisa n\u00e3o era bem o que pensava. O Iraque lembrava a pobreza de sua Guatemala e o calor fazia ferver o seu sangue latino.Logo foi destacado para uma miss\u00e3o de reconhecimento em uma cidade que n\u00e3o sabia pronunciar o nome. Mascando chicletes, com toda uma parafern\u00e1lia de muni\u00e7\u00f5es, equipamentos e armas, pensava estar protagonizando um daqueles filmes em que os \u201cmarines\u201d sempre vencem. Seguia o que seu sargento mandava fazer e gostava de colocar os \u00f3culos em que via no escuro, como se fosse dia. Era, enfim um americano. O \u201cJoe\u201d. Em um instante, Jos\u00e9 Guti\u00e9rrez estava morto. Uma bala perdida ou dirigida, nunca se saber\u00e1, o encontrou. Era o segundo americano morto em opera\u00e7\u00f5es no Iraque. Nem a\u00ed teve a gl\u00f3ria de ser o primeiro. Seu corpo foi resgatado e colocado em um caix\u00e3o de zinco enrolado em uma bandeira americana. Voltou no por\u00e3o de um avi\u00e3o de guerra. A Am\u00e9rica concedeu a Jos\u00e9 Guti\u00e9rrez a cidadania post mortem, n\u00e3o precisaria mais do \u201cgreen card\u201d.<\/p>\n<p>Escrito por Jo\u00e3o Soares Neto, a partir de not\u00edcia ver\u00eddica do jornal \u201cEl Clar\u00edn\u201d, de Buenos Aires, edi\u00e7\u00e3o de 29.03.2003<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 13\/04\/2003.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3720","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3720"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3720\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}