{"id":3723,"date":"2023-12-21T09:10:52","date_gmt":"2023-12-21T12:10:52","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/entrega-a-mae-terra\/"},"modified":"2023-12-21T09:10:52","modified_gmt":"2023-12-21T12:10:52","slug":"entrega-a-mae-terra","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/entrega-a-mae-terra\/","title":{"rendered":"ENTREGA \u00c0 M\u00c3E-TERRA"},"content":{"rendered":"<p>Voltei mais r\u00e1pido que esperava e desejava. As bandeiras me chamaram. Estava, novamente, na terra do chap\u00e9u Stetson e aonde foi selada a vit\u00f3ria de Bush sobre Gore. Foi agora em maio e eu me lembrei, mesmo sem querer, da entrega do Oscar deste ano, quando um americano meio fora do padr\u00e3o, Michael Moore, ganhou a estatueta de melhor document\u00e1rio com o filme \u201cTiros em Columbine\u201d, brandindo horrores contra o Sistema americano por ser uma na\u00e7\u00e3o louca por armas. A Am\u00e9rica \u00e9 muito complexa para ser descrita em um s\u00f3 filme. \u00c9 um pa\u00eds t\u00e3o multifacetado que cabe n\u00e3o s\u00f3 em \u201cTiros em Columbine\u201d, como no filme \u201cP\u00e3es e Rosas\u201d e em tantos outros.<br \/>\nVoltava \u00e0s pressas, a chamado de sentimentos. Os mesmos voos, a mesma estrada, as mesmas \u00e1rvores, a rua tranquila. Faltavam as bandeiras americana e brasileira. O p\u00f3rtico estava apenas com os aros. As bandeiras haviam sido retiradas. Estavam em outro lugar. E foi para l\u00e1 que fui.<br \/>\nEra uma igreja cat\u00f3lica. Bonita, moderna. Estrutura de a\u00e7o, mas toda recoberta por madeira. Parecendo ser o que n\u00e3o era. Ou era o que n\u00e3o parecia. L\u00e1 estavam as bandeiras, lado a lado. De p\u00e9. A diferen\u00e7a \u00e9 que havia algu\u00e9m deitado para sempre e outra tentando, com todas as suas for\u00e7as, manter-se de p\u00e9. Um padre jovem, alto, bem-apessoado, de voz canora, fazia \u00e0s vezes da casa. Houve c\u00e2nticos, discursos, ros\u00e1rio, missa de corpo presente, m\u00fasica sacra, gaitas irlandesas, encomenda\u00e7\u00e3o e a gentileza dos homens de preto que cuidavam de tudo.<br \/>\nEra chegada a hora de tomar outra estrada, afinal. Partimos para a cidade onde Jeb Bush trabalha. Chegamos \u00e0 noite e, em poucas horas, novamente, uma igreja. Desta vez ela era americana assumida, batista, infl\u00e1vel, de pl\u00e1stico, climatizada e poderia ser tamb\u00e9m uma quadra esportiva. As bandeiras j\u00e1 estavam l\u00e1. Haviam sido transportadas. Houve mais preces, c\u00e2nticos e at\u00e9 um longo discurso do Procurador Geral do Estado. Reminisc\u00eancias. A m\u00fasica cessou e apareceu a limusine. Sem limusine n\u00e3o estaria encerrada a participa\u00e7\u00e3o dos homens obrigados a estar ali. Tomamos a limusine. Gente das duas bandeiras. Vimos a estrada nos levando para uma floresta bonita. A limusine fez uma curva, saiu da estrada, e parou. Pis\u00e1vamos em ch\u00e3o batido. Descemos e ficamos em posi\u00e7\u00e3o. \u00c9ramos das duas bandeiras. Est\u00e1vamos ali para entregar \u00e0 m\u00e3e-terra algu\u00e9m que quis ficar em meio a ciprestes e a seus ancestrais, fora da estrada e ao reencontro de sua verdadeira natureza. P\u00e1ssaros cantaram e sa\u00edmos silentes.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 25\/05\/2003<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voltei mais r\u00e1pido que esperava e desejava. As bandeiras me chamaram. Estava, novamente, na terra do chap\u00e9u Stetson e aonde foi selada a vit\u00f3ria de Bush sobre Gore. Foi agora em maio e eu me lembrei, mesmo sem querer, da entrega do Oscar deste ano, quando um americano meio fora do padr\u00e3o, Michael Moore, ganhou a estatueta de melhor document\u00e1rio com o filme \u201cTiros em Columbine\u201d, brandindo horrores contra o Sistema americano por ser uma na\u00e7\u00e3o louca por armas. A Am\u00e9rica \u00e9 muito complexa para ser descrita em um s\u00f3 filme. \u00c9 um pa\u00eds t\u00e3o multifacetado que cabe n\u00e3o s\u00f3 em \u201cTiros em Columbine\u201d, como no filme \u201cP\u00e3es e Rosas\u201d e em tantos outros.<br \/>\nVoltava \u00e0s pressas, a chamado de sentimentos. Os mesmos voos, a mesma estrada, as mesmas \u00e1rvores, a rua tranquila. Faltavam as bandeiras americana e brasileira. O p\u00f3rtico estava apenas com os aros. As bandeiras haviam sido retiradas. Estavam em outro lugar. E foi para l\u00e1 que fui.<br \/>\nEra uma igreja cat\u00f3lica. Bonita, moderna. Estrutura de a\u00e7o, mas toda recoberta por madeira. Parecendo ser o que n\u00e3o era. Ou era o que n\u00e3o parecia. L\u00e1 estavam as bandeiras, lado a lado. De p\u00e9. A diferen\u00e7a \u00e9 que havia algu\u00e9m deitado para sempre e outra tentando, com todas as suas for\u00e7as, manter-se de p\u00e9. Um padre jovem, alto, bem-apessoado, de voz canora, fazia \u00e0s vezes da casa. Houve c\u00e2nticos, discursos, ros\u00e1rio, missa de corpo presente, m\u00fasica sacra, gaitas irlandesas, encomenda\u00e7\u00e3o e a gentileza dos homens de preto que cuidavam de tudo.<br \/>\nEra chegada a hora de tomar outra estrada, afinal. Partimos para a cidade onde Jeb Bush trabalha. Chegamos \u00e0 noite e, em poucas horas, novamente, uma igreja. Desta vez ela era americana assumida, batista, infl\u00e1vel, de pl\u00e1stico, climatizada e poderia ser tamb\u00e9m uma quadra esportiva. As bandeiras j\u00e1 estavam l\u00e1. Haviam sido transportadas. Houve mais preces, c\u00e2nticos e at\u00e9 um longo discurso do Procurador Geral do Estado. Reminisc\u00eancias. A m\u00fasica cessou e apareceu a limusine. Sem limusine n\u00e3o estaria encerrada a participa\u00e7\u00e3o dos homens obrigados a estar ali. Tomamos a limusine. Gente das duas bandeiras. Vimos a estrada nos levando para uma floresta bonita. A limusine fez uma curva, saiu da estrada, e parou. Pis\u00e1vamos em ch\u00e3o batido. Descemos e ficamos em posi\u00e7\u00e3o. \u00c9ramos das duas bandeiras. Est\u00e1vamos ali para entregar \u00e0 m\u00e3e-terra algu\u00e9m que quis ficar em meio a ciprestes e a seus ancestrais, fora da estrada e ao reencontro de sua verdadeira natureza. P\u00e1ssaros cantaram e sa\u00edmos silentes.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 25\/05\/2003<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3723","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3723"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3723\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}