{"id":3724,"date":"2023-12-21T09:10:52","date_gmt":"2023-12-21T12:10:52","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/o-inconformismo-do-olhar\/"},"modified":"2023-12-21T09:10:52","modified_gmt":"2023-12-21T12:10:52","slug":"o-inconformismo-do-olhar","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/o-inconformismo-do-olhar\/","title":{"rendered":"O INCONFORMISMO DO OLHAR"},"content":{"rendered":"<p>Quem olha com mais aten\u00e7\u00e3o em geral \u00e9 inconformado. O que v\u00ea n\u00e3o \u00e9 apenas o que se pretende mostrar. V\u00ea muito mais. Os olhos inconformados fazem leituras, filmam, auscultam, pintam e veem al\u00e9m da paisagem ou da pessoa. V\u00e3o l\u00e1 dentro da alma, da ess\u00eancia e sentem o outro em sua fisiognomonia das apar\u00eancias e dos gestos. E isso produz uma vis\u00e3o cr\u00edtica severa, a de entender o outro n\u00e3o pelo que diz, mas pelo que se infere da sua e da nossa hist\u00f3ria.<br \/>\nOs artistas, especialmente os pintores, escultores, compositores, cineastas, poetas e escritores t\u00eam, quase sempre, esse vi\u00e9s. N\u00e3o se contentam com a realidade aparente ou a aparente realidade. Fixam o olho e extraem a ess\u00eancia, aquilo que n\u00e3o fica exposto, embora seja uma fratura.<br \/>\nOs que viram o filme \u00b4Frida\u00b4 puderam observar que ela possu\u00eda inconformismo no olhar e isso a fez ser a pessoa que foi, mesmo tendo ao seu lado a figura consagrada do pintor e muralista Diego Rivera. Eram avan\u00e7ados para o seu tempo e os seus olhos viam mais do que o mundo mostrava. Despetalavam a realidade e com o seu inconformismo, a transformavam na loucura real em que viviam.<br \/>\nVirg\u00ednia Woolf, t\u00e3o pouco lida, mas muito comentada depois que um filme mostrou uma r\u00e9stia da sua vida, era outra pessoa com inconforma\u00e7\u00e3o no olhar. Acabei de ler \u00b4Mal de Amores\u00b4, da consagrada escritora mexicana Angelles Mastretta. A personagem principal, Em\u00edlia, tem o mesmo mal ou bem. N\u00e3o repousa o seu olhar apenas nas paisagens de Puebla, mas o distribui por todo o M\u00e9xico e d\u00e1 rasantes na Am\u00e9rica, sem nunca esquecer de seus dois amores, t\u00e3o diferentes quanto preservados e relevantes em sua vida singular e dupla. Por aqui h\u00e1 uma mulher de olhar inconformado: Nat\u00e9rcia Campos, cansou-se de ser filha, esposa e m\u00e3e, e deu a si o direito de construir uma casa com o olhar t\u00e3o amplo quanto os seus sonhos reprimidos. Sonhos transbordados em prosa t\u00e3o luminosa quanto a dram\u00e1tica trama de seu livro \u00b4A Casa\u00b4, um libelo pouco entendido, mesmo para os que o imaginaram ler com aten\u00e7\u00e3o. Ser\u00e1 preciso ter olhar inconformado para conseguir ver \u00b4A Casa\u00b4 em toda a sua plenitude e assombra\u00e7\u00f5es, este livro sobre pessoas, mas com almas e as lamas permeando o seu enredo.<br \/>\nTalvez valesse dizer aos namorados, festejados no pr\u00f3ximo dia 12, que deem vaz\u00e3o ao inconformismo preso em seus olhares. N\u00e3o finjam sentimentos e poupem quem espera amor e n\u00e3o apenas presentes. \u00c9 preciso ser verdadeiro neste tempo de tantas mentiras. \u00c9 preciso ter os olhos inconformados para adonar-se da vida, abr\u00ed-los para ver al\u00e9m. Depois, fech\u00e1-los e ouvir a sua voz interior. A que realmente conta.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 12\/06\/2003.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem olha com mais aten\u00e7\u00e3o em geral \u00e9 inconformado. O que v\u00ea n\u00e3o \u00e9 apenas o que se pretende mostrar. V\u00ea muito mais. Os olhos inconformados fazem leituras, filmam, auscultam, pintam e veem al\u00e9m da paisagem ou da pessoa. V\u00e3o l\u00e1 dentro da alma, da ess\u00eancia e sentem o outro em sua fisiognomonia das apar\u00eancias e dos gestos. E isso produz uma vis\u00e3o cr\u00edtica severa, a de entender o outro n\u00e3o pelo que diz, mas pelo que se infere da sua e da nossa hist\u00f3ria.<br \/>\nOs artistas, especialmente os pintores, escultores, compositores, cineastas, poetas e escritores t\u00eam, quase sempre, esse vi\u00e9s. N\u00e3o se contentam com a realidade aparente ou a aparente realidade. Fixam o olho e extraem a ess\u00eancia, aquilo que n\u00e3o fica exposto, embora seja uma fratura.<br \/>\nOs que viram o filme \u00b4Frida\u00b4 puderam observar que ela possu\u00eda inconformismo no olhar e isso a fez ser a pessoa que foi, mesmo tendo ao seu lado a figura consagrada do pintor e muralista Diego Rivera. Eram avan\u00e7ados para o seu tempo e os seus olhos viam mais do que o mundo mostrava. Despetalavam a realidade e com o seu inconformismo, a transformavam na loucura real em que viviam.<br \/>\nVirg\u00ednia Woolf, t\u00e3o pouco lida, mas muito comentada depois que um filme mostrou uma r\u00e9stia da sua vida, era outra pessoa com inconforma\u00e7\u00e3o no olhar. Acabei de ler \u00b4Mal de Amores\u00b4, da consagrada escritora mexicana Angelles Mastretta. A personagem principal, Em\u00edlia, tem o mesmo mal ou bem. N\u00e3o repousa o seu olhar apenas nas paisagens de Puebla, mas o distribui por todo o M\u00e9xico e d\u00e1 rasantes na Am\u00e9rica, sem nunca esquecer de seus dois amores, t\u00e3o diferentes quanto preservados e relevantes em sua vida singular e dupla. Por aqui h\u00e1 uma mulher de olhar inconformado: Nat\u00e9rcia Campos, cansou-se de ser filha, esposa e m\u00e3e, e deu a si o direito de construir uma casa com o olhar t\u00e3o amplo quanto os seus sonhos reprimidos. Sonhos transbordados em prosa t\u00e3o luminosa quanto a dram\u00e1tica trama de seu livro \u00b4A Casa\u00b4, um libelo pouco entendido, mesmo para os que o imaginaram ler com aten\u00e7\u00e3o. Ser\u00e1 preciso ter olhar inconformado para conseguir ver \u00b4A Casa\u00b4 em toda a sua plenitude e assombra\u00e7\u00f5es, este livro sobre pessoas, mas com almas e as lamas permeando o seu enredo.<br \/>\nTalvez valesse dizer aos namorados, festejados no pr\u00f3ximo dia 12, que deem vaz\u00e3o ao inconformismo preso em seus olhares. N\u00e3o finjam sentimentos e poupem quem espera amor e n\u00e3o apenas presentes. \u00c9 preciso ser verdadeiro neste tempo de tantas mentiras. \u00c9 preciso ter os olhos inconformados para adonar-se da vida, abr\u00ed-los para ver al\u00e9m. Depois, fech\u00e1-los e ouvir a sua voz interior. A que realmente conta.<\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nEscritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 12\/06\/2003.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3724","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3724"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3724\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}