{"id":3739,"date":"2023-12-21T09:10:53","date_gmt":"2023-12-21T12:10:53","guid":{"rendered":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/kennedy-40-anos-depois\/"},"modified":"2023-12-21T09:10:53","modified_gmt":"2023-12-21T12:10:53","slug":"kennedy-40-anos-depois","status":"publish","type":"post","link":"https:\/\/joaosoaresneto.com.br\/index.php\/2023\/12\/21\/kennedy-40-anos-depois\/","title":{"rendered":"KENNEDY, 40 ANOS DEPOIS"},"content":{"rendered":"<p>Ontem, 22 de novembro, fez 40 anos que John Fitzgerald Kennedy morreu. Todos lembram ou ouviram falar do fato acontecido em Dallas, Texas. Eu tinha 21 anos e, com a vaidade boba dos jovens, orgulhava-me de ter ganho, por concurso, uma bolsa de estudos para os Estados Unidos. Era uma bolsa privilegiada e, ao final, inclu\u00eda uma visita \u00e0 Casa Branca. N\u00e3o aos seus corredores, mas um encontro nos jardins internos com o Presidente, o jovem quarent\u00e3o John Kennedy.<br \/>\nPois bem, fomos todos de palet\u00f3 e gravata falar com o homem. Ele nos recebeu de terno azul marinho, camisa branca e gravata vermelha. Alto, olhos mi\u00fados com rugas ao redor, sardento, louro, jeito descontra\u00eddo, parecendo estar \u00e0 vontade. Era a \u00e9poca da \u201cAlian\u00e7a Para o Progresso\u201d, angariando simpatias e fustigando Fidel Castro, que j\u00e1 incomodava Washington.<br \/>\nA conversa foi amena, fotos tiradas, grava\u00e7\u00e3o pela Voz da Am\u00e9rica, apertos de m\u00e3o trocados e sa\u00edmos todos com os nossos minutos de gl\u00f3ria. N\u00e3o \u00e9 todo o dia que se \u00e9 recebido pelo Presidente. Voltamos ao Brasil em agosto e aqui as coisas j\u00e1 esquentavam. Jo\u00e3o Goulart sofria press\u00e3o por \u201creformas de base\u201d e os militares come\u00e7avam a se articular. Mas isto \u00e9 outra conversa.<br \/>\nExato no 22 de novembro de 1963 estava eu escrevendo na reda\u00e7\u00e3o dos Di\u00e1rios Associados, em Fortaleza, quando chegou a not\u00edcia do assassinato de Kennedy. Foi um alvoro\u00e7o geral e eu ajudei a compor a mat\u00e9ria. Meses depois, conheci uma mo\u00e7a, funcion\u00e1ria do Dnocs, que estava em Dallas no dia do atentado. Explico: o Dnocs fazia a manuten\u00e7\u00e3o de um avi\u00e3o seu em Dallas e ela, amiga do piloto, pegara uma carona. Ocorre que, Lee Oswald, suposto matador de Kennedy, quando era levado \u00e0 pris\u00e3o, foi assassinado diante das c\u00e2meras. Ela me disse que assistia \u00e0 TV quando reconheceu Jack Ruby, com quem havia dan\u00e7ado em uma boite. De repente, Ruby puxou de um rev\u00f3lver e matou Oswald. Soube-se depois que Ruby seria ligado \u00e0 M\u00e1fia. Mundo pequeno.<br \/>\nVoltando \u00e0 hist\u00f3ria, tem-se hoje quase certeza de que Lee Oswald, foi tido &#8211; e mantido &#8211; como o assassino oficial de Kennedy, mas o seu rifle de 13 d\u00f3lares, n\u00e3o teria a precis\u00e3o de dar os tr\u00eas tiros fatais, especialmente o \u00faltimo que destruiu o cr\u00e2nio do Presidente. A vers\u00e3o atual \u00e9 que o real homicida foi o corso Lucien Sarti, contratado pela M\u00e1fia. E como a mem\u00f3ria \u00e9 epis\u00f3dica, tudo isso me fez lembrar o caso dos compadres (por procura\u00e7\u00e3o, via consulado) nordestinos dos Kennedy. Z\u00e9 chegando alvoro\u00e7ado da ro\u00e7a e dizendo para Maria: \u201cMataram compadre Kennedy.\u201d. E Maria respondendo aflita: \u201cComo ficar\u00e1 a comadre Jacqueline?\u201d Pois \u00e9&#8230; <\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nescritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 23\/11\/2003.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ontem, 22 de novembro, fez 40 anos que John Fitzgerald Kennedy morreu. Todos lembram ou ouviram falar do fato acontecido em Dallas, Texas. Eu tinha 21 anos e, com a vaidade boba dos jovens, orgulhava-me de ter ganho, por concurso, uma bolsa de estudos para os Estados Unidos. Era uma bolsa privilegiada e, ao final, inclu\u00eda uma visita \u00e0 Casa Branca. N\u00e3o aos seus corredores, mas um encontro nos jardins internos com o Presidente, o jovem quarent\u00e3o John Kennedy.<br \/>\nPois bem, fomos todos de palet\u00f3 e gravata falar com o homem. Ele nos recebeu de terno azul marinho, camisa branca e gravata vermelha. Alto, olhos mi\u00fados com rugas ao redor, sardento, louro, jeito descontra\u00eddo, parecendo estar \u00e0 vontade. Era a \u00e9poca da \u201cAlian\u00e7a Para o Progresso\u201d, angariando simpatias e fustigando Fidel Castro, que j\u00e1 incomodava Washington.<br \/>\nA conversa foi amena, fotos tiradas, grava\u00e7\u00e3o pela Voz da Am\u00e9rica, apertos de m\u00e3o trocados e sa\u00edmos todos com os nossos minutos de gl\u00f3ria. N\u00e3o \u00e9 todo o dia que se \u00e9 recebido pelo Presidente. Voltamos ao Brasil em agosto e aqui as coisas j\u00e1 esquentavam. Jo\u00e3o Goulart sofria press\u00e3o por \u201creformas de base\u201d e os militares come\u00e7avam a se articular. Mas isto \u00e9 outra conversa.<br \/>\nExato no 22 de novembro de 1963 estava eu escrevendo na reda\u00e7\u00e3o dos Di\u00e1rios Associados, em Fortaleza, quando chegou a not\u00edcia do assassinato de Kennedy. Foi um alvoro\u00e7o geral e eu ajudei a compor a mat\u00e9ria. Meses depois, conheci uma mo\u00e7a, funcion\u00e1ria do Dnocs, que estava em Dallas no dia do atentado. Explico: o Dnocs fazia a manuten\u00e7\u00e3o de um avi\u00e3o seu em Dallas e ela, amiga do piloto, pegara uma carona. Ocorre que, Lee Oswald, suposto matador de Kennedy, quando era levado \u00e0 pris\u00e3o, foi assassinado diante das c\u00e2meras. Ela me disse que assistia \u00e0 TV quando reconheceu Jack Ruby, com quem havia dan\u00e7ado em uma boite. De repente, Ruby puxou de um rev\u00f3lver e matou Oswald. Soube-se depois que Ruby seria ligado \u00e0 M\u00e1fia. Mundo pequeno.<br \/>\nVoltando \u00e0 hist\u00f3ria, tem-se hoje quase certeza de que Lee Oswald, foi tido &#8211; e mantido &#8211; como o assassino oficial de Kennedy, mas o seu rifle de 13 d\u00f3lares, n\u00e3o teria a precis\u00e3o de dar os tr\u00eas tiros fatais, especialmente o \u00faltimo que destruiu o cr\u00e2nio do Presidente. A vers\u00e3o atual \u00e9 que o real homicida foi o corso Lucien Sarti, contratado pela M\u00e1fia. E como a mem\u00f3ria \u00e9 epis\u00f3dica, tudo isso me fez lembrar o caso dos compadres (por procura\u00e7\u00e3o, via consulado) nordestinos dos Kennedy. Z\u00e9 chegando alvoro\u00e7ado da ro\u00e7a e dizendo para Maria: \u201cMataram compadre Kennedy.\u201d. E Maria respondendo aflita: \u201cComo ficar\u00e1 a comadre Jacqueline?\u201d Pois \u00e9&#8230; <\/p>\n<p>Jo\u00e3o Soares Neto,<br \/>\nescritor<br \/>\nCR\u00d4NICA PUBLICADA NO DI\u00c1RIO DO NORDESTE EM 23\/11\/2003.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3739","post","type-post","status-publish","format-standard","hentry"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3739"}],"version-history":[{"count":0,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3739\/revisions"}],"wp:attachment":[{"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joaosoaresneto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}